{"id":11023,"date":"2024-05-19T09:31:29","date_gmt":"2024-05-19T07:31:29","guid":{"rendered":"https:\/\/pelemix.com\/crop\/baies\/fraises\/"},"modified":"2024-05-19T09:31:29","modified_gmt":"2024-05-19T07:31:29","slug":"fraises","status":"publish","type":"crop","link":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/","title":{"rendered":"Fraises"},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":11038,"parent":10887,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"crop-type":[],"class_list":["post-11023","crop","type-crop","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sacs de culture de fraises pour des rendements optimaux | Pelemix<\/title>\n<meta name=\"description\" content=\"Sacs de culture en fibre de coco durables pour une croissance optimis\u00e9e des fraises, favorisant un meilleur contr\u00f4le de l&#039;humidit\u00e9 et la sant\u00e9 des racines pour des rendements plus \u00e9lev\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sacs de culture de fraises pour des rendements optimaux | Pelemix\" \/>\n<meta property=\"og:description\" content=\"Sacs de culture en fibre de coco durables pour une croissance optimis\u00e9e des fraises, favorisant un meilleur contr\u00f4le de l&#039;humidit\u00e9 et la sant\u00e9 des racines pour des rendements plus \u00e9lev\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/\" \/>\n<meta property=\"og:site_name\" content=\"Pelemix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PelemixSpain\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/09\/Open-Top-list.png\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/\",\"url\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/\",\"name\":\"Sacs de culture de fraises pour des rendements optimaux | Pelemix\",\"isPartOf\":{\"@id\":\"https:\/\/pelemix.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/06\/Strawberries.svg\",\"datePublished\":\"2024-05-19T07:31:29+00:00\",\"description\":\"Sacs de culture en fibre de coco durables pour une croissance optimis\u00e9e des fraises, favorisant un meilleur contr\u00f4le de l'humidit\u00e9 et la sant\u00e9 des racines pour des rendements plus \u00e9lev\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#primaryimage\",\"url\":\"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/06\/Strawberries.svg\",\"contentUrl\":\"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/06\/Strawberries.svg\",\"width\":102,\"height\":88,\"caption\":\"Strawberries\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\/\/pelemix.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baies\",\"item\":\"https:\/\/pelemix.com\/fr\/crop\/baies\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fraises\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pelemix.com\/fr\/#website\",\"url\":\"https:\/\/pelemix.com\/fr\/\",\"name\":\"Pelemix\",\"description\":\"Pelemix is a leader in the coir \u2013 coco peat substrate market for Hydroponics growers and nurseries. Our coir is used worldwide as a growing media for various hydroponics crops\",\"publisher\":{\"@id\":\"https:\/\/pelemix.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pelemix.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pelemix.com\/fr\/#organization\",\"name\":\"Pelemix - Professionals In Coir Substrates\",\"alternateName\":\"Pelemix\",\"url\":\"https:\/\/pelemix.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/pelemix.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/09\/Open-Top-list.png\",\"contentUrl\":\"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/09\/Open-Top-list.png\",\"width\":667,\"height\":700,\"caption\":\"Pelemix - Professionals In Coir Substrates\"},\"image\":{\"@id\":\"https:\/\/pelemix.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PelemixSpain\",\"https:\/\/www.linkedin.com\/company\/642244\/admin\/feed\/posts\",\"https:\/\/www.youtube.com\/@pelemix4178\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sacs de culture de fraises pour des rendements optimaux | Pelemix","description":"Sacs de culture en fibre de coco durables pour une croissance optimis\u00e9e des fraises, favorisant un meilleur contr\u00f4le de l'humidit\u00e9 et la sant\u00e9 des racines pour des rendements plus \u00e9lev\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/","og_locale":"fr_FR","og_type":"article","og_title":"Sacs de culture de fraises pour des rendements optimaux | Pelemix","og_description":"Sacs de culture en fibre de coco durables pour une croissance optimis\u00e9e des fraises, favorisant un meilleur contr\u00f4le de l'humidit\u00e9 et la sant\u00e9 des racines pour des rendements plus \u00e9lev\u00e9s.","og_url":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/","og_site_name":"Pelemix","article_publisher":"https:\/\/www.facebook.com\/PelemixSpain","og_image":[{"width":667,"height":700,"url":"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/09\/Open-Top-list.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/","url":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/","name":"Sacs de culture de fraises pour des rendements optimaux | Pelemix","isPartOf":{"@id":"https:\/\/pelemix.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#primaryimage"},"image":{"@id":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#primaryimage"},"thumbnailUrl":"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/06\/Strawberries.svg","datePublished":"2024-05-19T07:31:29+00:00","description":"Sacs de culture en fibre de coco durables pour une croissance optimis\u00e9e des fraises, favorisant un meilleur contr\u00f4le de l'humidit\u00e9 et la sant\u00e9 des racines pour des rendements plus \u00e9lev\u00e9s.","breadcrumb":{"@id":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#primaryimage","url":"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/06\/Strawberries.svg","contentUrl":"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/06\/Strawberries.svg","width":102,"height":88,"caption":"Strawberries"},{"@type":"BreadcrumbList","@id":"https:\/\/pelemix.com\/fr\/crop\/baies\/fraises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hogar","item":"https:\/\/pelemix.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Baies","item":"https:\/\/pelemix.com\/fr\/crop\/baies\/"},{"@type":"ListItem","position":3,"name":"Fraises"}]},{"@type":"WebSite","@id":"https:\/\/pelemix.com\/fr\/#website","url":"https:\/\/pelemix.com\/fr\/","name":"Pelemix","description":"Pelemix is a leader in the coir \u2013 coco peat substrate market for Hydroponics growers and nurseries. Our coir is used worldwide as a growing media for various hydroponics crops","publisher":{"@id":"https:\/\/pelemix.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pelemix.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pelemix.com\/fr\/#organization","name":"Pelemix - Professionals In Coir Substrates","alternateName":"Pelemix","url":"https:\/\/pelemix.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pelemix.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/09\/Open-Top-list.png","contentUrl":"https:\/\/pelemix.com\/wp-content\/uploads\/2023\/09\/Open-Top-list.png","width":667,"height":700,"caption":"Pelemix - Professionals In Coir Substrates"},"image":{"@id":"https:\/\/pelemix.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PelemixSpain","https:\/\/www.linkedin.com\/company\/642244\/admin\/feed\/posts","https:\/\/www.youtube.com\/@pelemix4178"]}]}},"_links":{"self":[{"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/crop\/11023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/crop"}],"about":[{"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/types\/crop"}],"author":[{"embeddable":true,"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/crop\/11023\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/crop\/10887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/media\/11038"}],"wp:attachment":[{"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/media?parent=11023"}],"wp:term":[{"taxonomy":"crop-type","embeddable":true,"href":"https:\/\/pelemix.com\/fr\/wp-json\/wp\/v2\/crop-type?post=11023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}